{"id":12,"count":4,"description":"","link":"https:\/\/eventech3d.es\/index.php\/category\/news\/","name":"NEWS","slug":"news","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NEWS archivos - EVENTECH 3D<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eventech3d.es\/index.php\/category\/news\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NEWS archivos - EVENTECH 3D\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eventech3d.es\/index.php\/category\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"EVENTECH 3D\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/eventech3d.es\\\/index.php\\\/category\\\/news\\\/\",\"url\":\"https:\\\/\\\/eventech3d.es\\\/index.php\\\/category\\\/news\\\/\",\"name\":\"NEWS archivos - EVENTECH 3D\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eventech3d.es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eventech3d.es\\\/index.php\\\/category\\\/news\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eventech3d.es\\\/index.php\\\/category\\\/news\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eventech3d.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NEWS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eventech3d.es\\\/#website\",\"url\":\"https:\\\/\\\/eventech3d.es\\\/\",\"name\":\"EVENTECH 3D\",\"description\":\"Producci\u00f3n t\u00e9cnica para eventos y Renders 3d\",\"publisher\":{\"@id\":\"https:\\\/\\\/eventech3d.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eventech3d.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eventech3d.es\\\/#organization\",\"name\":\"EVENTECH 3D\",\"url\":\"https:\\\/\\\/eventech3d.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eventech3d.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eventech3d.es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/g19904-8.png\",\"contentUrl\":\"https:\\\/\\\/eventech3d.es\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/g19904-8.png\",\"width\":342,\"height\":342,\"caption\":\"EVENTECH 3D\"},\"image\":{\"@id\":\"https:\\\/\\\/eventech3d.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NEWS archivos - EVENTECH 3D","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eventech3d.es\/index.php\/category\/news\/","og_locale":"es_ES","og_type":"article","og_title":"NEWS archivos - EVENTECH 3D","og_url":"https:\/\/eventech3d.es\/index.php\/category\/news\/","og_site_name":"EVENTECH 3D","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/eventech3d.es\/index.php\/category\/news\/","url":"https:\/\/eventech3d.es\/index.php\/category\/news\/","name":"NEWS archivos - EVENTECH 3D","isPartOf":{"@id":"https:\/\/eventech3d.es\/#website"},"breadcrumb":{"@id":"https:\/\/eventech3d.es\/index.php\/category\/news\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/eventech3d.es\/index.php\/category\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eventech3d.es\/"},{"@type":"ListItem","position":2,"name":"NEWS"}]},{"@type":"WebSite","@id":"https:\/\/eventech3d.es\/#website","url":"https:\/\/eventech3d.es\/","name":"EVENTECH 3D","description":"Producci\u00f3n t\u00e9cnica para eventos y Renders 3d","publisher":{"@id":"https:\/\/eventech3d.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eventech3d.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/eventech3d.es\/#organization","name":"EVENTECH 3D","url":"https:\/\/eventech3d.es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eventech3d.es\/#\/schema\/logo\/image\/","url":"https:\/\/eventech3d.es\/wp-content\/uploads\/2025\/06\/g19904-8.png","contentUrl":"https:\/\/eventech3d.es\/wp-content\/uploads\/2025\/06\/g19904-8.png","width":342,"height":342,"caption":"EVENTECH 3D"},"image":{"@id":"https:\/\/eventech3d.es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/eventech3d.es\/index.php\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventech3d.es\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/eventech3d.es\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/eventech3d.es\/index.php\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}